{"id":433,"date":"2021-10-16T18:50:53","date_gmt":"2021-10-16T16:50:53","guid":{"rendered":"https:\/\/finaccessvalue.es\/?page_id=433"},"modified":"2026-05-04T22:14:42","modified_gmt":"2026-05-04T20:14:42","slug":"prensa","status":"publish","type":"page","link":"https:\/\/finaccessvalue.es\/en\/prensa\/","title":{"rendered":"PRESS"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"433\" class=\"elementor elementor-433\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66eb8555 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"66eb8555\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 2600 131.1\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c4080b5\" data-id=\"3c4080b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20ecc3fd elementor-widget elementor-widget-heading\" data-id=\"20ecc3fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mant\u00e9nte al d\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b704d6 elementor-widget elementor-widget-heading\" data-id=\"24b704d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Comunicaci\u00f3n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0043a2b elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"0043a2b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd93453\" data-id=\"fd93453\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-863994e premium-blog-cta-full-yes premium-blog-align-left elementor-widget elementor-widget-premium-addon-blog\" data-id=\"863994e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;premium_blog_layout&quot;:&quot;masonry&quot;,&quot;premium_blog_columns_number&quot;:&quot;25%&quot;,&quot;premium_blog_infinite_scroll&quot;:&quot;yes&quot;,&quot;filter_flag&quot;:&quot;cat&quot;,&quot;premium_blog_grid&quot;:&quot;yes&quot;,&quot;premium_blog_columns_number_tablet&quot;:&quot;50%&quot;,&quot;premium_blog_columns_number_mobile&quot;:&quot;100%&quot;,&quot;scroll_to_offset&quot;:&quot;yes&quot;}\" data-widget_type=\"premium-addon-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"premium-blog-filter\">\n\t\t\t<ul class=\"premium-blog-filters-container\">\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a href=\"javascript:;\" class=\"category active\" data-filter=\"*\">\n\t\t\t\t\t\t\tTodas\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"javascript:;\" class=\"category\" data-filter=\"audios\">\n\t\t\t\t\t\t\t\tAudios\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"javascript:;\" class=\"category\" data-filter=\"comentario-mercados\">\n\t\t\t\t\t\t\t\tComentario Mercados\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"javascript:;\" class=\"category\" data-filter=\"prensa\">\n\t\t\t\t\t\t\t\tPRESS\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"javascript:;\" class=\"category\" data-filter=\"videos\">\n\t\t\t\t\t\t\t\tV\u00eddeos\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<div class=\"premium-blog-wrap  premium-blog-masonry\" data-page=\"433\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-mayo-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 12 mayo 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 12, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNo hay viento favorable para quien no sabe d\u00f3nde va.\u201d S\u00e9neca Los mercados de un vistazo. En un nuevo capi\u0301tulo del conflicto con Ira\u0301n, ayer Donald Trump califico\u0301 la propuesta de acuerdo remitida por<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-mayo-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-mayo-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 5 mayo 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 5, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLos guerreros victoriosos ganan primero y luego van a la guerra, mientras que los guerreros derrotados van primero a la guerra y luego tratan de ganar.\u201d Sun Tzu Ayer vivimos una nueva jornada de<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-mayo-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-abril-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 28 abril 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 28, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl tiempo es amigo de los negocios excelentes y enemigo de los mediocres.\u201d Warren Buffet Con las negociaciones de paz en Oriente Medio en el alero (ayer Ir\u00e1n envi\u00f3 una propuesta en la que<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-abril-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-abril-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 22 abril 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 22, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa guerra es la continuaci\u00f3n de la pol\u00edtica por otros medios.\u201d Carl von Clausewitz Ayer, a escasas horas de que espirara el alto el fuego entre EE.UU, Israel e Ir\u00e1n, vivimos el en\u00e9simo episodio<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-abril-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-abril-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 14 abril 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 14, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa pol\u00edtica es el arte de buscar problemas, encontrarlos, realizar un diagn\u00f3stico falso y aplicar despu\u00e9s remedios equivocados.\u201d Groucho Marx Con todo lo que est\u00e1 cayendo, la \u00faltima noticia el cierre del Estrecho de<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-abril-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-abril-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 7 abril 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 7, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSi no est\u00e1 bien, no lo hagas, si no es verdad, no lo digas.\u201d Marco Aurelio Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-abril-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-marzo-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 24 marzo 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 24, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEn la Bolsa, con frecuencia, hay que cerrar los ojos para ver mejor.\u201d Andre Kostolany Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-marzo-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-marzo-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 17 marzo 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 17, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cTodo lo que necesitas saber sobre el mercado est\u00e1 en la historia.\u201d Peter Lynch Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores SA.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-marzo-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-marzo-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 10 marzo 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 10, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNo hay viento favorable para el que no sabe d\u00f3nde va.\u201d S\u00e9neca Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores SA. Este informe<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-marzo-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 25 febrero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 25, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cTrata a las personas como un fin, nunca como un medio para un fin.\u201d Kant Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-febrero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 17 febrero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 17, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cQuienes creen que el dinero lo hace todo terminan haciendo todo por dinero.\u201d Voltaire Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores SA.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-febrero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-febrero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 10 febrero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 10, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201c\u201cPocas veces pensamos en lo que tenemos, pero siempre en lo que nos falta.\u201d Schopenhauer Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-febrero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-enero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 27 enero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 27, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa cualidad m\u00e1s importante de un inversor es el temperamento, no el intelecto.\u201d Warren Buffett Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-enero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-enero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 13 enero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 13, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa pereza viaja tan despacio que la pobreza no tarda en alcanzarla.\u201d Benjamin Franklin Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores SA.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-enero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-fondos-finaccess-y-entrevista-perspectivas-2026\/\" target=\"_self\">\n\t\t\t\tBalance Fondos Finaccess y entrevista perspectivas 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 8, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Le\u00a0deseamos un Feliz A\u00f1o 2026 y lo mejor para este a\u00f1o que acabamos de empezar.Adjuntamos las rentabilidades de los fondos de Finaccess Value en 2025: Finaccess Global \u00a05,57%Finaccess Renta Fija Corto Plazo \u00a02,60%Finaccess Horizonte<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-fondos-finaccess-y-entrevista-perspectivas-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-enero-2026\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 8 enero 2026\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 8, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNo puedes hacer un buen trato con una mala persona.\u201d Warren Buffet Los mercados de un vistazo. El mundo esta\u0301 revuelto, de eso no cabe ninguna duda. Venezuela y Groenlandia se unen a los<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-enero-2026\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/recomendamos-prudencia-priorizando-el-margen-de-seguridad-en-las-inversiones\/\" target=\"_self\">\n\t\t\t\tRecomendamos prudencia, priorizando el margen de seguridad en las inversiones\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 7, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Con ya seis a\u00f1os de andadura en Espa\u00f1a, la agencia de valores\u00a0Finaccess Value\u00a0sigue confiando en un enfoque en el valor a largo plazo y una gesti\u00f3n rigurosa del riesgo. La matriz,\u00a0Grupo Finaccess, acumula una<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/recomendamos-prudencia-priorizando-el-margen-de-seguridad-en-las-inversiones\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container videos\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/videos\/los-mercados-comienzan-la-primera-semana-completa-de-negociacion-del-ano-con-la-mirada-puesta-en-venezuela-tertulia-de-mercados-de-capital-intereconomia\/\" target=\"_self\">\n\t\t\t\tLos mercados comienzan la primera semana completa de negociaci\u00f3n del a\u00f1o con la mirada puesta en Venezuela | Tertulia de mercados de Capital Intereconom\u00eda  \u25b6\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 5, 2026<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Despu\u00e9s de la detenci\u00f3n de Maduro, los inversores reaccionan ante la posibilidad de un cambio de r\u00e9gimen que podr\u00eda transformar por completo el sector energ\u00e9tico del pa\u00eds. El foco est\u00e1 ahora en si el<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/videos\/los-mercados-comienzan-la-primera-semana-completa-de-negociacion-del-ano-con-la-mirada-puesta-en-venezuela-tertulia-de-mercados-de-capital-intereconomia\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/2026-un-ano-para-reajustar-carteras\/\" target=\"_self\">\n\t\t\t\t2026, un a\u00f1o para reajustar carteras\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 28, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">2026, un a\u00f1o para reajustar carteras.-\u00a0Al igual que no deber\u00edamos juzgar un libro por su portada, en los mercados financieros har\u00edamos mal en quedarnos \u00fanicamente en el saldo \u2014excepcional, por otro lado\u2014 de los<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/2026-un-ano-para-reajustar-carteras\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/como-generar-ingresos-recurrentes\/\" target=\"_self\">\n\t\t\t\t\u00bfC\u00f3mo generar ingresos recurrentes?\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 18, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Por Pilar Bravo, directora de Desarrollo de Negocio en\u00a0Finaccess Value Salvo sorpresa de \u00faltima hora, el a\u00f1o 2025 va a cerrar como un a\u00f1o de fuertes rentabilidades en los mercados financieros que, sin embargo,<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/como-generar-ingresos-recurrentes\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-abuso-de-la-deuda-por-parte-de-los-estados-amenaza-con-convertirse-en-estructural-a-largo-plazo-supone-un-problema-mucho-mas-grave-que-la-ia\/\" target=\"_self\">\n\t\t\t\tEl abuso de la deuda por parte de los Estados amenaza con convertirse en estructural. A largo plazo, supone un problema mucho m\u00e1s grave que la IA\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 30, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Lola Jaquotot, Gestora Senior de Renta Variable en Finaccess Value. \u00abLos mercados a veces est\u00e1n cegados y no ven m\u00e1s all\u00e1\u00bb \u201cPodr\u00eda decir que siempre he querido ser\u00a0gestora de fondos de inversi\u00f3n, pero la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-abuso-de-la-deuda-por-parte-de-los-estados-amenaza-con-convertirse-en-estructural-a-largo-plazo-supone-un-problema-mucho-mas-grave-que-la-ia\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-caracter-como-factor-diferencial-del-inversor\/\" target=\"_self\">\n\t\t\t\tEl car\u00e1cter como factor diferencial del inversor\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 29, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Conocer la historia del gestor permite entender su trayectoria, sus decisiones y, sobre todo, su personalidad. En la novela\u00a0El buscavidas\u00a0(1959), de Walter Tevis, hay un pasaje en el que el protagonista, Eddie Felson \u2013interpretado<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-caracter-como-factor-diferencial-del-inversor\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-noviembre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 18 noviembre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 18, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa envidia es una declaraci\u00f3n de inferioridad.\u201d Napole\u00f3n Bonaparte Los mercados de un vistazo. Continu\u0301an las correcciones en las bolsas. Despue\u0301s de meses ininterrumpidos de subidas, este momento teni\u0301a que llegar. Las explicaciones que<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-noviembre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-la-agencia-con-vision-internacional-y-talento-espanol\/\" target=\"_self\">\n\t\t\t\tFinaccess Value, la agencia con visi\u00f3n internacional y talento espa\u00f1ol\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 14, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Como\u00a0agencia de valores\u00a0del\u00a0Grupo Finaccess, Finaccess Value proporciona soluciones de inversi\u00f3n personalizadas e independientes, con un enfoque en el valor a largo plazo y una gesti\u00f3n rigurosa del riesgo. Est\u00e1 orientada a clientes que buscan<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-la-agencia-con-vision-internacional-y-talento-espanol\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-noviembre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 11 noviembre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 11, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEn su mayor\u00eda, es la p\u00e9rdida la que nos ense\u00f1a el valor de las cosas.\u201d\u00a0 Arthur Schopenhauer Los mercados de un vistazo. La noticia de que el Senado estadounidense habi\u0301a acordado ayer una proposicio\u0301n<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-noviembre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-octubre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 21 octubre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 21, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa experiencia no es lo que sucede, sino lo que haces con lo que te sucede.\u201d\u00a0 Aldous Huxley Los mercados de un vistazo. Est\u00e1 claro que los inversores est\u00e1n ansiosos de agarrarse a las<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-octubre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-octubre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | 7 octubre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 7, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer ni escribir, sino aquellos que no sepan aprender, desaprender y reaprender.\u201d\u00a0 Alvin Toffler Los mercados de un vistazo. Continuamos con el alza<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-octubre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-septiembre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  30 septiembre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 30, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201c\u201cA veces, el fracaso consiste simplemente en desviarte del camino equivocado y llevarte al correcto.\u201d Paul Tudor Jones Los mercados de un vistazo. Estamos asistiendo a jornadas en los que los \u00edndices burs\u00e1tiles se<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-septiembre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-16-septiembre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  16 septiembre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 16, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl hombre que anticipa la llegada de los problemas les quita el poder cuando aparecen..\u201d S\u00e9neca Los mercados de un vistazo. Este u\u0301ltimo \u201carreo\u0301n\u201d de las bolsas, que ha llevado al Standard&amp;Poors y al<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-16-septiembre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-9-septiembre-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  9 septiembre 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 9, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLos mejores inversores no tienen un objetivo de rentabilidad; se centran primero en el riesgo, y s\u00f3lo entonces deciden si la rentabilidad proyectada justifica tomar cada riesgo particular.\u201d Seth Klarman Los mercados de un<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-9-septiembre-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-fondo-finaccess-estrategia-dividendo-mixto-obtiene-la-maxima-calificacion-de-morningstar\/\" target=\"_self\">\n\t\t\t\tEl fondo Finaccess Estrategia Dividendo Mixto obtiene la m\u00e1xima calificaci\u00f3n de Morningstar\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 8, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">El fondo Finaccess Estrategia Dividendo Mixto obtiene la m\u00e1xima calificaci\u00f3n de Morningstar.-\u00a0 El fondo Finaccess Estrategia Dividendo Mixto ha sido recientemente reconocido con la m\u00e1xima calificaci\u00f3n de 5 estrellas por parte de Morningstar, un<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-fondo-finaccess-estrategia-dividendo-mixto-obtiene-la-maxima-calificacion-de-morningstar\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/no-es-momento-de-plantarse-pero-si-de-tener-mas-cautela\/\" target=\"_self\">\n\t\t\t\tNo es momento de plantarse pero s\u00ed de tener m\u00e1s cautela\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 6, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Por el equipo de Finaccess Value AV Nos encontramos en un mundo inestable donde los mercados est\u00e1n claramente marcados por la volatilidad derivada de las tensiones geopol\u00edticas y comerciales, las pol\u00edticas de los bancos<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/no-es-momento-de-plantarse-pero-si-de-tener-mas-cautela\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-julio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  29 julio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 29, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSi los cerdos pudieran votar, el hombre que trae el balde de comida ser\u00eda elegido una y otra vez\u2026sin importar cuantos de ellos haya sacrificado antes.\u201d Nicolas Maquiavelo Los mercados de un vistazo. Tras<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-julio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-julio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  15 julio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 15, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cM\u00e1s se pierde por indecisi\u00f3n que por una mala decisi\u00f3n.\u201d Cicer\u00f3n Los mercados de un vistazo. Como en el cuento de Pedro y el lobo, los mercados respondieron con indiferencia al anuncio de Trump<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-julio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-julio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  8 julio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 8, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa capacidad de observar sin juzgar es la forma m\u00e1s alta de inteligencia.\u201d Krishnamurti Los mercados de un vistazo. Hoy es el u\u0301ltimo di\u0301a antes de conocer los aranceles que EE.UU impondra\u0301 a las<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-julio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-julio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  3 julio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 3, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa capacidad de observar sin juzgar es la forma m\u00e1s alta de inteligencia.\u201d Krishnamurti Los mercados de un vistazo. A nivel macro, sin lugar a duda la noticia estuvo ayer en la aprobacio\u0301n por<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-julio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-junio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  24 junio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 24, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa guerra no es un fen\u00f3meno independiente, sino la continuaci\u00f3n de la pol\u00edtica por diferentes medios.\u201d Carl P. G. von Clausewitz Los mercados de un vistazo. Al final, la sangre no lleg\u00f3 al r\u00edo.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-junio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-av-ideas-para-diversificar-las-carteras-de-renta-fija\/\" target=\"_self\">\n\t\t\t\tFinaccess Value AV: Ideas para diversificar las carteras de renta fija\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 20, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Por el equipo de Finaccess Value AV Nos encontramos en un mundo inestable donde los mercados est\u00e1n claramente marcados por la volatilidad derivada de las tensiones geopol\u00edticas y comerciales, las pol\u00edticas de los bancos<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-av-ideas-para-diversificar-las-carteras-de-renta-fija\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/dividendo-con-futuro-cuchara-de-calidad-cuando-el-ruido-asusta-la-filosofia-de-finaccess-value\/\" target=\"_self\">\n\t\t\t\tDividendo con futuro &#8216;cuchara&#8217; de calidad cuando el ruido asusta, la filosof\u00eda de Finaccess Value\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 20, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Alfonso de Gregorio, director de inversiones de Finaccess Value, defiende la vigencia de una estrategia basada en dividendos sostenibles y gesti\u00f3n activa \u00bfC\u00f3mo valoran desde Finaccess la evoluci\u00f3n de los mercados en esta primera<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/dividendo-con-futuro-cuchara-de-calidad-cuando-el-ruido-asusta-la-filosofia-de-finaccess-value\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/vision-patrimonialista-y-generacion-de-rentas-claves-del-fondo-finaccess-estrategia-dividendo-mixto\/\" target=\"_self\">\n\t\t\t\tVisi\u00f3n patrimonialista y generaci\u00f3n de rentas, claves del fondo Finaccess Estrategia Dividendo Mixto\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 19, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Visi\u00f3n patrimonialista y generaci\u00f3n de rentas, claves del fondo Finaccess Estrategia Dividendo Mixto.-\u00a0 En un momento en el que los inversores priorizan la estabilidad, la previsibilidad de resultados y una gesti\u00f3n activa que combine<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/vision-patrimonialista-y-generacion-de-rentas-claves-del-fondo-finaccess-estrategia-dividendo-mixto\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-inversion-esg-bajo-la-lupa\/\" target=\"_self\">\n\t\t\t\tLa inversi\u00f3n ESG, bajo la lupa\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 14, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">El p\u00e9ndulo sobre estos activos en Europa se ha movido a un punto m\u00e1s pragm\u00e1tico e inteligente y menos extremista. En los \u00faltimos tiempos hemos asistido a una fuerte p\u00e9rdida del impulso (e incluso<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-inversion-esg-bajo-la-lupa\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-junio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  10 junio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 10, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSi lograste enga\u00f1ar a una persona, no quiere decir que sea tonta, quiere decir que confi\u00f3 en ti m\u00e1s de lo que te merec\u00edas.\u201d Charles Bukowski Los mercados de un vistazo. Los mercados se<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-junio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-junio-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  3 junio 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 3, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSi lograste enga\u00f1ar a una persona, no quiere decir que sea tonta, quiere decir que confi\u00f3 en ti m\u00e1s de lo que te merec\u00edas.\u201d Charles Bukowski Los mercados de un vistazo. Parece que en<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-junio-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/oportunidades-de-inversion-tras-el-apagon-electrico\/\" target=\"_self\">\n\t\t\t\tOportunidades de inversi\u00f3n tras el apag\u00f3n el\u00e9ctrico\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>June 2, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): Oportunidades de inversi\u00f3n tras el apag\u00f3n el\u00e9ctrico.-\u00a0El reciente apag\u00f3n el\u00e9ctrico registrado en\u00a0Espa\u00f1a\u00a0\u2014cuyas causas a\u00fan no han sido determinadas\u2014 ha puesto de manifiesto la importancia cr\u00edtica de contar con un\u00a0sistema energ\u00e9tico<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/oportunidades-de-inversion-tras-el-apagon-electrico\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-mayo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  27 mayo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 27, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLos dos guerreros m\u00e1s poderosos son la paciencia y el tiempo.\u201d Leon Tolstoi Los mercados de un vistazo. Los mercados estaban demasiado complacientes. Eso debi\u00f3 de pensar Donald Trump el pasado viernes cuando decidi\u00f3<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-mayo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/lo-que-hizo-biden-de-subir-el-gasto\/\" target=\"_self\">\n\t\t\t\tLo que hizo Biden de subir el gasto en la parte m\u00e1s madura del ciclo, va en contra de toda l\u00f3gica. Varios de los problemas que afrontamos hoy tienen su origen en esa decisi\u00f3n\u00bb\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 25, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">David, \u00bfse presenta a nuestros lectores, por favor? \u201cMe llamo\u00a0David Ardura, soy CoDirector de Inversiones de\u00a0Finaccess Value, llevo trabajando en mercados 27 a\u00f1os, de los cuales los \u00faltimos 17 se han centrado en la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/lo-que-hizo-biden-de-subir-el-gasto\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-20-mayo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  20 mayo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 20, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEs peligroso tener raz\u00f3n cuando el gobierno est\u00e1 equivocado.\u201d Voltaire Los mercados de un vistazo. Ni siquiera la rebaja de la m\u00e1xima calificaci\u00f3n crediticia de EE.UU por parte de Moodys (cr\u00f3nica de una muerte<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-20-mayo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/invertir-por-dividendos-estabilidad-y-rentabilidad-en-tiempos-de-incertidumbre\/\" target=\"_self\">\n\t\t\t\tInvertir por dividendos, estabilidad y rentabilidad en tiempos de incertidumbre\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 16, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Alfonso de Gregorio (Finaccess Value):Invertir por dividendos, estabilidad y rentabilidad en tiempos de incertidumbre.-\u00a0Entrevista a Alfonso de Gregorio, director de inversiones de Finaccess Value, en el podcast\u00a0Tiempo de Inversi\u00f3n En un contexto marcado por<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/invertir-por-dividendos-estabilidad-y-rentabilidad-en-tiempos-de-incertidumbre\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-mayo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  13 mayo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 13, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl conocimiento es poder, y aquellos que buscan aprender tendr\u00e1n una ventaja.\u201d VICTOR HUGO Los mercados de un vistazo. Pues resulta que, despu\u00e9s de toda la volatilidad de los mercados, de todas las noticias<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-mayo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-momento-de-invertir-en-una-estrategia-de-generacion-de-rentas\/\" target=\"_self\">\n\t\t\t\t\u00bfEs momento de invertir en una estrategia de generaci\u00f3n de rentas?\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 12, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">En el pasado webinar organizado por EFPA Espa\u00f1a, exploramos c\u00f3mo la estrategia de generaci\u00f3n de rentas puede adaptarse a diferentes perfiles de riesgo, su comportamiento en contextos hist\u00f3ricos y las formas pr\u00e1cticas de implementarlo<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-momento-de-invertir-en-una-estrategia-de-generacion-de-rentas\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-buen-momento-para-invertir-siguiendo-una-estrategia-de-generacion-de-rentas\/\" target=\"_self\">\n\t\t\t\t\u00bfEs buen momento para invertir siguiendo una estrategia de generaci\u00f3n de rentas?\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 9, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Por el equipo de\u00a0Finaccess Value AV Trump apenas lleva tres meses en la presidencia, aunque m\u00e1s bien parecer\u00edan tres a\u00f1os. Sin entrar en la monta\u00f1a rusa que supone esta guerra arancelaria con el quita<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-buen-momento-para-invertir-siguiendo-una-estrategia-de-generacion-de-rentas\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-6-mayo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  6 mayo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>May 6, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa necesidad de tener siempre la raz\u00f3n es signo de una mente vulgar.\u201d Albert Camus Los mercados de un vistazo. Continuamos con unos mercados en calma, hu\u00e9rfanos, por ahora, de noticias relevantes y de<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-6-mayo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-abril-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  30 abril 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 30, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cVemos las cosas, no como son, sino como somos nosotros.\u201d Inmanuel Kant Los mercados de un vistazo. Llevamos varias sesiones de tranquilidad en los mercados gracias a las formas y mensajes ma\u0301s moderados de<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-abril-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/sector-sanitario-oportunidad-de-inversion-e-impacto-positivo-en-el-bienestar-de-la-sociedad\/\" target=\"_self\">\n\t\t\t\tSector sanitario, oportunidad de inversi\u00f3n e impacto positivo en el bienestar de la sociedad\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 25, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): Sector sanitario, oportunidad de inversi\u00f3n e impacto positivo en el bienestar de la sociedad .- En este entorno de volatilidad e incertidumbre en el que estamos, las compa\u00f1\u00edas de salud<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/sector-sanitario-oportunidad-de-inversion-e-impacto-positivo-en-el-bienestar-de-la-sociedad\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-23-abril-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  23 abril 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 23, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSolo hay una manera de evitar la cr\u00edtica: no hacer nada, no decir nada y no ser nadie.\u201d Arist\u00f3teles Los mercados de un vistazo. Tres meses lleva Trump como presidente de EE.UU. y parece<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-23-abril-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-abril-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  8 abril 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 8, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSe\u00a0temeroso cuando los otros sean\u00a0avariciosos\u00a0y\u00a0avaricioso cuando\u00a0los otros sean temerosos\u201d Warren Buffet Los mercados de un vistazo. Volatilidad y fort\u00edsimas ca\u00eddas es lo que llevan sufriendo los mercados desde el anuncio de los aranceles por<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-abril-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-1-abril-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  1 abril 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>April 1, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cBueno es en verdad adquirir, pero mucho mejor conservar\u201d Goethe Los mercados de un vistazo. A la espera de que man\u0303ana el presidente Trump desgrane su poli\u0301tica arancelaria, los inversores europeos optaron por recoger<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-1-abril-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-marzo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  25 marzo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 25, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cM\u00e1s vale fracasar con honor que ganar con fraude.\u201d S\u00f3crates Los mercados de un vistazo. La informacio\u0301n aparecida ayer tanto en Bloomberg como en el Wall Streeet Journal en las que se adelantaba que<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-marzo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-impacto-de-invertir-en-inclusion-financiera\/\" target=\"_self\">\n\t\t\t\tEl impacto de invertir en inclusi\u00f3n financiera\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 24, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): El impacto de invertir en inclusi\u00f3n financiera.-\u00a0 Seg\u00fan los datos publicados en el \u00faltimo informe del\u00a0Banco Mundial\u00a0sobre el estado de la Inclusi\u00f3n Econ\u00f3mica 2024, aproximadamente el 90% de los 700<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-impacto-de-invertir-en-inclusion-financiera\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-ruido-y-la-furia\/\" target=\"_self\">\n\t\t\t\tEl ruido y la furia\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 22, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">DESCARGAR NOTICIA<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-ruido-y-la-furia\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-marzo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  18 marzo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 20, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cVemos las cosas, no como son, sino como somos nosotros.\u201d Emmanuel Kant Los mercados de un vistazo. Unos datos de Sentimiento de Consumidor estadounidense menos desastrosos de lo esperado actuaron como ba\u0301lsamo sobre los<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-marzo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-credito-de-calidad-y-la-deuda-publica-claves-en-2025\/\" target=\"_self\">\n\t\t\t\tEl cr\u00e9dito de calidad y la deuda p\u00fablica, claves en 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 14, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">David Ardura (Finaccess Value): \u201cEl cr\u00e9dito de calidad y la deuda p\u00fablica, claves en 2025\u201d.-\u00a0El mercado de\u00a0renta fija\u00a0en 2025\u00a0ofrece\u00a0oportunidades atractivas\u00a0en un entorno de\u00a0tipos de inter\u00e9s a la baja en Europa\u00a0y una creciente divergencia entre<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-credito-de-calidad-y-la-deuda-publica-claves-en-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-marzo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  11 marzo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 11, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa pereza viaja tan despacio que la pobreza no tarda en alcanzarla.\u201d Benjamin Franklin Los mercados de un vistazo. Las declaraciones de Trump a una cadena de televisi\u00f3n en las que no descartaba una<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-marzo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-4-marzo-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  4 marzo 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 4, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl idiota considera falso todo lo que es incapaz de entender.\u201d Santo Tom\u00e1s de Aquino Los mercados de un vistazo. Ayer volvimos a constatar la divergencia que, desde principios de a\u00f1o, se est\u00e1 produciendo<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-4-marzo-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/ganadores-del-mandato-de-trump\/\" target=\"_self\">\n\t\t\t\tGanadores del mandato de Trump\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>March 4, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): Ganadores del mandato de Trump.- El inicio del mandato de Trump ha marcado claramente la agenda pol\u00edtica mundial y el paso de los mercados. As\u00ed vemos c\u00f3mo los mercados se<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/ganadores-del-mandato-de-trump\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/efpa-espana-y-finaccess-value-se-unen-para-impulsar-el-asesoramiento-financiero-de-calidad\/\" target=\"_self\">\n\t\t\t\tEFPA Espa\u00f1a y Finaccess Value se unen para impulsar el asesoramiento financiero de calidad\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 27, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">EFPA Espa\u00f1a\u00a0ha alcanzado un acuerdo de colaboraci\u00f3n con\u00a0Finaccess Value, agencia de valores perteneciente al grupo financiero Finaccess, fundado hace veinticinco an\u0303os y con presencia en diferentes pai\u0301ses como\u00a0Espa\u00f1a, Estados Unidos y Me\u0301xico. Gracias a<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/efpa-espana-y-finaccess-value-se-unen-para-impulsar-el-asesoramiento-financiero-de-calidad\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  25 febrero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 25, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNo es que tengamos poco tiempo, sino que perdemos mucho.\u201d S\u00e9neca Los mercados de un vistazo. Las contin\u00faas amenazas de Trump en materia arancelaria y los bandazos en asuntos geopol\u00edticos, comienzan a hacer estragos<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-febrero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  18 febrero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 18, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl problema de nuestra \u00e9poca consiste en que sus hombres no quieren ser \u00fatiles, sino importantes.\u201d Winston Churchill Los mercados de un vistazo. Con el mercado estadounidense cerrado por la conmemoraci\u00f3n del d\u00eda del<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-febrero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-febrero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  11 febrero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 11, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa paciencia es amarga, pero sus frutos son dulces.\u201d Rousseau Los mercados de un vistazo. Parece que, al final, los mercados se acaban acostumbrando a vivir con la incertidumbre arancelaria. Ayer, ante el anuncio<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-febrero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/transicion-energetica-catalizadores-y-oportunidades-para-2025\/\" target=\"_self\">\n\t\t\t\tTransici\u00f3n energ\u00e9tica. Catalizadores y oportunidades para 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 5, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): Transici\u00f3n energ\u00e9tica. Catalizadores y oportunidades para 2025. El a\u00f1o 2024 present\u00f3 importantes desaf\u00edos macroecon\u00f3micos y sectoriales para las inversiones en transici\u00f3n energ\u00e9tica. Los costes de financiaci\u00f3n persistentemente elevados, junto con<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/transicion-energetica-catalizadores-y-oportunidades-para-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-4-febrero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  4 febrero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>February 4, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl hombre sabio querr\u00e1 estar siempre con quien sea mejor que \u00e9l.\u201d Plat\u00f3n Los mercados de un vistazo. Sorprendentemente, los mercados se vieron ayer sacudidos por las medidas arancelarias que Donald Trump anuncio\u0301 que<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-4-febrero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-enero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  28 enero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 28, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cMuch\u00edsima gente se ha vuelto pesimista por financiar a optimistas.\u201d C.T. Los mercados de un vistazo. Lo que en principio iba a ser una jornada de transici\u00f3n, con los ojos de los inversores puestos<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-enero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-dificil-trabajo-de-predecir-a-trump\/\" target=\"_self\">\n\t\t\t\tEl dif\u00edcil trabajo de predecir a Trump\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 23, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Si algo une a los analistas en este inicio de a\u00f1o, es la certeza de que los mercados financieros de 2025 estar\u00e1n profundamente influenciados por las decisiones de la reci\u00e9n estrenada administraci\u00f3n de\u00a0Donald Trump.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-dificil-trabajo-de-predecir-a-trump\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-enero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  21 enero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 21, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa vida no es siempre una cuesti\u00f3n de tener buenas cartas, sino, a veces, de jugar bien una mala mano.\u201d Jack London Los mercados de un vistazo. Con el mercado estadounidense cerrado debido a<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-enero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-enero-2025\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  14 enero 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>January 14, 2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cDec\u00eds vosotros que los tiempos son malos, sed vosotros mejores y los tiempos ser\u00e1n mejores, vosotros sois el tiempo.\u201d San Agust\u00edn Los mercados de un vistazo. Desde que conocimos el dato de desempleo en<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-enero-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-del-ano-y-vision-de-mercado-para-2025\/\" target=\"_self\">\n\t\t\t\tBalance del a\u00f1o y visi\u00f3n de mercado para 2025\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 17, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Si miramos el saldo de los activos de riesgo en este 2024, nos encontramos con que el resultado s\u00f3lo se puede calificar como positivo. La mayor\u00eda de activos y mercados van a cerrar el<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-del-ano-y-vision-de-mercado-para-2025\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-diciembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  17 diciembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 17, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201c\u00a1No solo investigues y eval\u00faes el mercado, sino tambi\u00e9n las decisiones de los inversionistas a tu alrededor!\u201d John Bogle Los mercados de un vistazo. Nueva jornada la de ayer de recortes en bolsa europea,<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-diciembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-diciembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  10 diciembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 10, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cHe aprendido a buscar mi felicidad limitando mis deseos en vez de satisfacerlos.\u201d John Stuart Mill Los mercados de un vistazo. La jornada de ayer vino marcada por la filtracio\u0301n de las principales ideas<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-diciembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-diciembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  3 diciembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>December 3, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSoy un optimista irreprimible, pero baso mi optimismo en hechos s\u00f3lidos.\u201d Mahatma Gandhi Los mercados de un vistazo. Los mercados han arrancado diciembre manteniendo la din\u00e1mica del mes de noviembre, especialmente apoyados en la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-diciembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/en-renta-fija-es-hora-de-alargar-los-vencimientos-hasta-el-rango-de-3-a-5-anos\/\" target=\"_self\">\n\t\t\t\tEn renta fija, es hora de alargar los vencimientos hasta el rango de 3 a 5 a\u00f1os\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 30, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">La renta fija ha vuelto, para alegr\u00eda de los inversores m\u00e1s moderados.\u00a0Pese a que pueden seguir, quiz\u00e1, traumatizados por la hecatombe de 2022 -un a\u00f1o en el que el bono de Estados Unidos a<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/en-renta-fija-es-hora-de-alargar-los-vencimientos-hasta-el-rango-de-3-a-5-anos\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-26-noviembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  26 noviembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 26, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cPoseer acciones es como tener ni\u00f1os: no tengas m\u00e1s de las que puedas controlar.\u201d Peter Lynch Los mercados de un vistazo. El anuncio del nombramiento del nuevo Secretario del Tesoro estadounidense de la administracio\u0301n<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-26-noviembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-19-noviembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  19 noviembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 19, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLos grandes avances de la civilizaci\u00f3n ya sean en arquitectura o pintura, en ciencia o literatura, jam\u00e1s han venido de un gobierno central.\u201d Milton Friedman Los mercados de un vistazo. Jornada de transici\u00f3n la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-19-noviembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/tras-la-victoria-de-trump-flexibilidad-ante-la-incertidumbre\/\" target=\"_self\">\n\t\t\t\tTras la victoria de Trump: Flexibilidad ante la incertidumbre\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 18, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Tras la victoria de Trump: Flexibilidad ante la incertidumbre, por David Ardura (Finaccess Value). La cita electoral del pasado martes en EEUU\u00a0estaba marcada en nuestras agendas como el \u00faltimo gran evento de este 2024.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/tras-la-victoria-de-trump-flexibilidad-ante-la-incertidumbre\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-noviembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  12 noviembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 12, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEn los negocios pr\u00e1cticos de la vida, no es la fe la que salva, sino la desconfianza.\u201d Napole\u00f3n Bonaparte Los mercados de un vistazo. Contin\u00faan las alzas en las bolsas estadounidenses despu\u00e9s de la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-noviembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-noviembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  5 noviembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>November 5, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl contribuyente es una persona que trabaja para el Gobierno, pero sin haber hecho las oposiciones a funcionario.\u201d Ronald Regan Los mercados de un vistazo. Las bolsas mundiales siguen, sorprendentemente, sin inmutarse ante las<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-noviembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-octubre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados |  29 octubre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 29, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNada es suficiente para el que no se conforma con poco.\u201d Epicuro Los mercados de un vistazo. La jornada de ayer vino marcada, sin lugar a duda, por la fuerte bajada del precio del<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-octubre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/pilar-bravo-finaccess-value-como-mejorar-nuestro-bienestar-a-traves-de-un-fondo-de-inversion\/\" target=\"_self\">\n\t\t\t\tC\u00f3mo mejorar nuestro bienestar a trav\u00e9s de un fondo de inversi\u00f3n\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 28, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Pilar Bravo (Finaccess Value): C\u00f3mo mejorar nuestro bienestar a trav\u00e9s de un fondo de inversi\u00f3n.-\u00a0El 88% de la gente valora muy favorablemente el compromiso social de las empresas con temas como el empleo, la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/pilar-bravo-finaccess-value-como-mejorar-nuestro-bienestar-a-traves-de-un-fondo-de-inversion\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-octubre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 22 octubre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 22, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cThe market is better at predicting the news than the news is at predicting the market.\u201d Gerarld Loeb Los mercados de un vistazo. La jornada de ayer estuvo marcada por el fuerte rebote en<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-octubre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-octubre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 15 octubre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 15, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cNothing is so permanent as a temporary government program.\u201d Milton Friedman Los mercados de un vistazo. Las bolsas cerraron ayer con nuevos avances, continuando con la tendencia de la semana pasada y permitiendo que<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-octubre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-octubre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 8 octubre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 8, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cInvertir en acciones es un arte, no una ciencia, y las personas que han sido entrenadas para cuantificar r\u00edgidamente todo tienen una gran desventaja.\u201d Peter Lynch Los mercados de un vistazo. Las bolsas europeas<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-octubre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-nueva-normalidad-y-el-esta-vez-todo-es-diferente\/\" target=\"_self\">\n\t\t\t\tLa nueva normalidad y el \u2018esta vez todo es diferente\u2019\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 5, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">No es natural que las Bolsas convivan mucho tiempo con valoraciones rozando el percentil 100 respecto a su media hist\u00f3rica Como inversores, y como seres humanos, somos capaces de justificar casi cualquier situaci\u00f3n, por<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-nueva-normalidad-y-el-esta-vez-todo-es-diferente\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-1-octubre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 1 octubre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>October 1, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cLa inflaci\u00f3n es como el pecado; cada gobierno la denuncia, pero cada gobierno la practica.\u201d Georg Christoph Lichtenberg Los mercados de un vistazo. La sesi\u00f3n de ayer en Europa estuvo marcada, sin lugar a<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-1-octubre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-septiembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 24 septiembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 24, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEl asunto m\u00e1s b\u00e1sico no es qu\u00e9 es lo mejor, sino qui\u00e9n debe decidir qu\u00e9 es lo mejor.\u201d Thomas Sowell Los mercados de un vistazo. La sesi\u00f3n de ayer en Europa estuvo marcada, sin<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-septiembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-septiembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 17 septiembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 17, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cUn banco es un lugar en el que prestan a usted un paraguas cuando hace buen tiempo y se lo piden cuando empieza a llover\u201d Robert Lee Frost Los mercados de un vistazo. A<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-septiembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-septiembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 11 septiembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 11, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEn bolsa, con frecuencia, hay que cerrar los ojos para ver mejor\u201d Andre Kostolany Los mercados de un vistazo. Jornada marcada en Europa, sin lugar a dudas, por las malas noticias provenientes del sector<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-septiembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-asesora-el-nuevo-fondo-de-renta-fija-a-vencimiento-gestionado-por-inversis\/\" target=\"_self\">\n\t\t\t\tFINACCESS VALUE ASESORA EL NUEVO FONDO DE RENTA FIJA A VENCIMIENTO GESTIONADO POR INVERSIS\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 7, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">La agencia de valores&nbsp;Finaccess Value&nbsp;ampl\u00eda su gama de fondos de inversi\u00f3n con el lanzamiento de&nbsp;Finaccess Horizonte 2027,&nbsp;un fondo de renta fija gestionado por&nbsp;Inversis Gesti\u00f3n&nbsp;que en el que Finaccess Value ejerce como asesor en la<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-asesora-el-nuevo-fondo-de-renta-fija-a-vencimiento-gestionado-por-inversis\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container prensa\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-inversor-conservador-ante-el-cambio-de-politica-monetaria\/\" target=\"_self\">\n\t\t\t\tEl inversor conservador ante el cambio de pol\u00edtica monetaria\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 4, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">El panorama macroecon\u00f3mico actual es especialmente interesante. El cruce de caminos que supone el momento inmediato anterior a un cambio de ciclo de pol\u00edtica monetaria no es algo que se vea todos los a\u00f1os,<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-inversor-conservador-ante-el-cambio-de-politica-monetaria\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-septiembre-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 3 septiembre 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>September 3, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cSi ves un plan r\u00e1pido para enriquecerte, es otra persona que trata de enriquecerse contigo r\u00e1pidamente\u201d Noval Ravikant Los mercados de un vistazo. Con el mercado estadounidense cerrado en la sesi\u00f3n de ayer, los<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-septiembre-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/16-julio-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 16 julio 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 16, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cEs mayor el temor que el da\u00f1o futuro\u201d Ludovico Ariosto Los mercados de un vistazo. Comenzamos la campa\u00f1a de presentaci\u00f3n de resultados empresariales correspondientes al segundo trimestre del a\u00f1o y comienza a haber sorpresas.<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/16-julio-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container comentario-mercados\" data-total=\"3\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/9-julio-2024\/\" target=\"_self\">\n\t\t\t\tComentario de Mercados | <br> 9 julio 2024\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>July 9, 2024<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">\u201cAl controlar tus emociones empiezas a ver las cosas a un nivel superior.\u201d Ray Dalio Los mercados de un vistazo. Jornada vol\u00e1til la que vivimos ayer en los mercados europeos, en los que los<\/p><div class=\"premium-blog-excerpt-link-wrap\"><a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/9-julio-2024\/\" target=\"_self\" class=\"premium-blog-excerpt-link elementor-button\">Leer m\u00e1s \u00bb<\/a><\/div>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d64409 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d64409\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fa70c8\" data-id=\"6fa70c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba34ae elementor-posts__hover-none elementor-grid-4 elementor-posts--thumbnail-none elementor-posts--align-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"4ba34ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6073 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-mayo-2026\/\">\n\t\t\t\tComentario de Mercados | 12 mayo 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cNo hay viento favorable para quien no sabe d\u00f3nde va.\u201d S\u00e9neca Los mercados de un vistazo. En un nuevo capi\u0301tulo del conflicto con Ira\u0301n, ayer Donald Trump<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-12-mayo-2026\/\" aria-label=\"Read more about Comentario de Mercados | 12 mayo 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 12, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6030 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-mayo-2026\/\">\n\t\t\t\tComentario de Mercados | 5 mayo 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLos guerreros victoriosos ganan primero y luego van a la guerra, mientras que los guerreros derrotados van primero a la guerra y luego tratan de ganar.\u201d Sun<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-5-mayo-2026\/\" aria-label=\"Read more about Comentario de Mercados | 5 mayo 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 5, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5997 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-abril-2026\/\">\n\t\t\t\tComentario de Mercados | 28 abril 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEl tiempo es amigo de los negocios excelentes y enemigo de los mediocres.\u201d Warren Buffet Con las negociaciones de paz en Oriente Medio en el alero (ayer<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-28-abril-2026\/\" aria-label=\"Read more about Comentario de Mercados | 28 abril 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 28, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5989 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-abril-2026\/\">\n\t\t\t\tComentario de Mercados | 22 abril 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa guerra es la continuaci\u00f3n de la pol\u00edtica por otros medios.\u201d Carl von Clausewitz Ayer, a escasas horas de que espirara el alto el fuego entre EE.UU,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-22-abril-2026\/\" aria-label=\"Read more about Comentario de Mercados | 22 abril 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 22, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5981 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-abril-2026\/\">\n\t\t\t\tComentario de Mercados | 14 abril 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa pol\u00edtica es el arte de buscar problemas, encontrarlos, realizar un diagn\u00f3stico falso y aplicar despu\u00e9s remedios equivocados.\u201d Groucho Marx Con todo lo que est\u00e1 cayendo, la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-14-abril-2026\/\" aria-label=\"Read more about Comentario de Mercados | 14 abril 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 14, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5976 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-abril-2026\/\">\n\t\t\t\tComentario de Mercados | 7 abril 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cSi no est\u00e1 bien, no lo hagas, si no es verdad, no lo digas.\u201d Marco Aurelio Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-abril-2026\/\" aria-label=\"Read more about Comentario de Mercados | 7 abril 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 7, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5968 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-marzo-2026\/\">\n\t\t\t\tComentario de Mercados | 24 marzo 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEn la Bolsa, con frecuencia, hay que cerrar los ojos para ver mejor.\u201d Andre Kostolany Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-marzo-2026\/\" aria-label=\"Read more about Comentario de Mercados | 24 marzo 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMarch 24, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5961 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-marzo-2026\/\">\n\t\t\t\tComentario de Mercados | 17 marzo 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cTodo lo que necesitas saber sobre el mercado est\u00e1 en la historia.\u201d Peter Lynch Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-marzo-2026\/\" aria-label=\"Read more about Comentario de Mercados | 17 marzo 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMarch 17, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5949 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-marzo-2026\/\">\n\t\t\t\tComentario de Mercados | 10 marzo 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cNo hay viento favorable para el que no sabe d\u00f3nde va.\u201d S\u00e9neca Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-marzo-2026\/\" aria-label=\"Read more about Comentario de Mercados | 10 marzo 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMarch 10, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5942 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2026\/\">\n\t\t\t\tComentario de Mercados | 25 febrero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cTrata a las personas como un fin, nunca como un medio para un fin.\u201d Kant Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-25-febrero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 25 febrero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tFebruary 25, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5935 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-febrero-2026\/\">\n\t\t\t\tComentario de Mercados | 17 febrero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cQuienes creen que el dinero lo hace todo terminan haciendo todo por dinero.\u201d Voltaire Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-17-febrero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 17 febrero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tFebruary 17, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5925 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-febrero-2026\/\">\n\t\t\t\tComentario de Mercados | 10 febrero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201c\u201cPocas veces pensamos en lo que tenemos, pero siempre en lo que nos falta.\u201d Schopenhauer Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-febrero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 10 febrero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tFebruary 10, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5912 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-enero-2026\/\">\n\t\t\t\tComentario de Mercados | 27 enero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa cualidad m\u00e1s importante de un inversor es el temperamento, no el intelecto.\u201d Warren Buffett Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-enero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 27 enero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 27, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5819 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-enero-2026\/\">\n\t\t\t\tComentario de Mercados | 13 enero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa pereza viaja tan despacio que la pobreza no tarda en alcanzarla.\u201d Benjamin Franklin Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-enero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 13 enero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 13, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5876 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-fondos-finaccess-y-entrevista-perspectivas-2026\/\">\n\t\t\t\tBalance Fondos Finaccess y entrevista perspectivas 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Le\u00a0deseamos un Feliz A\u00f1o 2026 y lo mejor para este a\u00f1o que acabamos de empezar.Adjuntamos las rentabilidades de los fondos de Finaccess Value en 2025: Finaccess Global<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/balance-fondos-finaccess-y-entrevista-perspectivas-2026\/\" aria-label=\"Read more about Balance Fondos Finaccess y entrevista perspectivas 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 8, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5805 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-enero-2026\/\">\n\t\t\t\tComentario de Mercados | 8 enero 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cNo puedes hacer un buen trato con una mala persona.\u201d Warren Buffet Los mercados de un vistazo. El mundo esta\u0301 revuelto, de eso no cabe ninguna duda.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-enero-2026\/\" aria-label=\"Read more about Comentario de Mercados | 8 enero 2026\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 8, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5795 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/recomendamos-prudencia-priorizando-el-margen-de-seguridad-en-las-inversiones\/\">\n\t\t\t\tRecomendamos prudencia, priorizando el margen de seguridad en las inversiones\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Con ya seis a\u00f1os de andadura en Espa\u00f1a, la agencia de valores\u00a0Finaccess Value\u00a0sigue confiando en un enfoque en el valor a largo plazo y una gesti\u00f3n rigurosa<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/recomendamos-prudencia-priorizando-el-margen-de-seguridad-en-las-inversiones\/\" aria-label=\"Read more about Recomendamos prudencia, priorizando el margen de seguridad en las inversiones\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 7, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5800 post type-post status-publish format-standard hentry category-videos tag-noticias tag-videos\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/videos\/los-mercados-comienzan-la-primera-semana-completa-de-negociacion-del-ano-con-la-mirada-puesta-en-venezuela-tertulia-de-mercados-de-capital-intereconomia\/\">\n\t\t\t\tLos mercados comienzan la primera semana completa de negociaci\u00f3n del a\u00f1o con la mirada puesta en Venezuela | Tertulia de mercados de Capital Intereconom\u00eda  \u25b6\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Despu\u00e9s de la detenci\u00f3n de Maduro, los inversores reaccionan ante la posibilidad de un cambio de r\u00e9gimen que podr\u00eda transformar por completo el sector energ\u00e9tico del pa\u00eds.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/videos\/los-mercados-comienzan-la-primera-semana-completa-de-negociacion-del-ano-con-la-mirada-puesta-en-venezuela-tertulia-de-mercados-de-capital-intereconomia\/\" aria-label=\"Read more about Los mercados comienzan la primera semana completa de negociaci\u00f3n del a\u00f1o con la mirada puesta en Venezuela | Tertulia de mercados de Capital Intereconom\u00eda  \u25b6\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJanuary 5, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5787 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/2026-un-ano-para-reajustar-carteras\/\">\n\t\t\t\t2026, un a\u00f1o para reajustar carteras\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>2026, un a\u00f1o para reajustar carteras.-\u00a0Al igual que no deber\u00edamos juzgar un libro por su portada, en los mercados financieros har\u00edamos mal en quedarnos \u00fanicamente en el<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/2026-un-ano-para-reajustar-carteras\/\" aria-label=\"Read more about 2026, un a\u00f1o para reajustar carteras\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tDecember 28, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5782 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/como-generar-ingresos-recurrentes\/\">\n\t\t\t\t\u00bfC\u00f3mo generar ingresos recurrentes?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por Pilar Bravo, directora de Desarrollo de Negocio en\u00a0Finaccess Value Salvo sorpresa de \u00faltima hora, el a\u00f1o 2025 va a cerrar como un a\u00f1o de fuertes rentabilidades<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/como-generar-ingresos-recurrentes\/\" aria-label=\"Read more about \u00bfC\u00f3mo generar ingresos recurrentes?\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tDecember 18, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5768 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-abuso-de-la-deuda-por-parte-de-los-estados-amenaza-con-convertirse-en-estructural-a-largo-plazo-supone-un-problema-mucho-mas-grave-que-la-ia\/\">\n\t\t\t\tEl abuso de la deuda por parte de los Estados amenaza con convertirse en estructural. A largo plazo, supone un problema mucho m\u00e1s grave que la IA\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lola Jaquotot, Gestora Senior de Renta Variable en Finaccess Value. \u00abLos mercados a veces est\u00e1n cegados y no ven m\u00e1s all\u00e1\u00bb \u201cPodr\u00eda decir que siempre he querido<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-abuso-de-la-deuda-por-parte-de-los-estados-amenaza-con-convertirse-en-estructural-a-largo-plazo-supone-un-problema-mucho-mas-grave-que-la-ia\/\" aria-label=\"Read more about El abuso de la deuda por parte de los Estados amenaza con convertirse en estructural. A largo plazo, supone un problema mucho m\u00e1s grave que la IA\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tNovember 30, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5764 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-caracter-como-factor-diferencial-del-inversor\/\">\n\t\t\t\tEl car\u00e1cter como factor diferencial del inversor\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Conocer la historia del gestor permite entender su trayectoria, sus decisiones y, sobre todo, su personalidad. En la novela\u00a0El buscavidas\u00a0(1959), de Walter Tevis, hay un pasaje en<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-caracter-como-factor-diferencial-del-inversor\/\" aria-label=\"Read more about El car\u00e1cter como factor diferencial del inversor\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tNovember 29, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5741 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-noviembre-2025\/\">\n\t\t\t\tComentario de Mercados | 18 noviembre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa envidia es una declaraci\u00f3n de inferioridad.\u201d Napole\u00f3n Bonaparte Los mercados de un vistazo. Continu\u0301an las correcciones en las bolsas. Despue\u0301s de meses ininterrumpidos de subidas, este<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-18-noviembre-2025\/\" aria-label=\"Read more about Comentario de Mercados | 18 noviembre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tNovember 18, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5758 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-la-agencia-con-vision-internacional-y-talento-espanol\/\">\n\t\t\t\tFinaccess Value, la agencia con visi\u00f3n internacional y talento espa\u00f1ol\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Como\u00a0agencia de valores\u00a0del\u00a0Grupo Finaccess, Finaccess Value proporciona soluciones de inversi\u00f3n personalizadas e independientes, con un enfoque en el valor a largo plazo y una gesti\u00f3n rigurosa del<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-la-agencia-con-vision-internacional-y-talento-espanol\/\" aria-label=\"Read more about Finaccess Value, la agencia con visi\u00f3n internacional y talento espa\u00f1ol\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tNovember 14, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5731 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-noviembre-2025\/\">\n\t\t\t\tComentario de Mercados | 11 noviembre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEn su mayor\u00eda, es la p\u00e9rdida la que nos ense\u00f1a el valor de las cosas.\u201d\u00a0 Arthur Schopenhauer Los mercados de un vistazo. La noticia de que el<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-11-noviembre-2025\/\" aria-label=\"Read more about Comentario de Mercados | 11 noviembre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tNovember 11, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5716 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-octubre-2025\/\">\n\t\t\t\tComentario de Mercados | 21 octubre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa experiencia no es lo que sucede, sino lo que haces con lo que te sucede.\u201d\u00a0 Aldous Huxley Los mercados de un vistazo. Est\u00e1 claro que los<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-21-octubre-2025\/\" aria-label=\"Read more about Comentario de Mercados | 21 octubre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tOctober 21, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5690 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-octubre-2025\/\">\n\t\t\t\tComentario de Mercados | 7 octubre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer ni escribir, sino aquellos que no sepan aprender, desaprender y reaprender.\u201d\u00a0 Alvin Toffler Los mercados<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-7-octubre-2025\/\" aria-label=\"Read more about Comentario de Mercados | 7 octubre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tOctober 7, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5673 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-septiembre-2025\/\">\n\t\t\t\tComentario de Mercados |  30 septiembre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201c\u201cA veces, el fracaso consiste simplemente en desviarte del camino equivocado y llevarte al correcto.\u201d Paul Tudor Jones Los mercados de un vistazo. Estamos asistiendo a jornadas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-30-septiembre-2025\/\" aria-label=\"Read more about Comentario de Mercados |  30 septiembre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tSeptember 30, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5640 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-16-septiembre-2025\/\">\n\t\t\t\tComentario de Mercados |  16 septiembre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEl hombre que anticipa la llegada de los problemas les quita el poder cuando aparecen..\u201d S\u00e9neca Los mercados de un vistazo. Este u\u0301ltimo \u201carreo\u0301n\u201d de las bolsas,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-16-septiembre-2025\/\" aria-label=\"Read more about Comentario de Mercados |  16 septiembre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tSeptember 16, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5604 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-9-septiembre-2025\/\">\n\t\t\t\tComentario de Mercados |  9 septiembre 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLos mejores inversores no tienen un objetivo de rentabilidad; se centran primero en el riesgo, y s\u00f3lo entonces deciden si la rentabilidad proyectada justifica tomar cada riesgo<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-9-septiembre-2025\/\" aria-label=\"Read more about Comentario de Mercados |  9 septiembre 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tSeptember 9, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5621 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-fondo-finaccess-estrategia-dividendo-mixto-obtiene-la-maxima-calificacion-de-morningstar\/\">\n\t\t\t\tEl fondo Finaccess Estrategia Dividendo Mixto obtiene la m\u00e1xima calificaci\u00f3n de Morningstar\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>El fondo Finaccess Estrategia Dividendo Mixto obtiene la m\u00e1xima calificaci\u00f3n de Morningstar.-\u00a0 El fondo Finaccess Estrategia Dividendo Mixto ha sido recientemente reconocido con la m\u00e1xima calificaci\u00f3n de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/el-fondo-finaccess-estrategia-dividendo-mixto-obtiene-la-maxima-calificacion-de-morningstar\/\" aria-label=\"Read more about El fondo Finaccess Estrategia Dividendo Mixto obtiene la m\u00e1xima calificaci\u00f3n de Morningstar\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tSeptember 8, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5623 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/no-es-momento-de-plantarse-pero-si-de-tener-mas-cautela\/\">\n\t\t\t\tNo es momento de plantarse pero s\u00ed de tener m\u00e1s cautela\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por el equipo de Finaccess Value AV Nos encontramos en un mundo inestable donde los mercados est\u00e1n claramente marcados por la volatilidad derivada de las tensiones geopol\u00edticas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/no-es-momento-de-plantarse-pero-si-de-tener-mas-cautela\/\" aria-label=\"Read more about No es momento de plantarse pero s\u00ed de tener m\u00e1s cautela\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tSeptember 6, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5583 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-julio-2025\/\">\n\t\t\t\tComentario de Mercados |  29 julio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cSi los cerdos pudieran votar, el hombre que trae el balde de comida ser\u00eda elegido una y otra vez\u2026sin importar cuantos de ellos haya sacrificado antes.\u201d Nicolas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-29-julio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  29 julio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJuly 29, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5569 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-julio-2025\/\">\n\t\t\t\tComentario de Mercados |  15 julio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cM\u00e1s se pierde por indecisi\u00f3n que por una mala decisi\u00f3n.\u201d Cicer\u00f3n Los mercados de un vistazo. Como en el cuento de Pedro y el lobo, los mercados<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-15-julio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  15 julio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJuly 15, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5554 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-julio-2025\/\">\n\t\t\t\tComentario de Mercados |  8 julio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa capacidad de observar sin juzgar es la forma m\u00e1s alta de inteligencia.\u201d Krishnamurti Los mercados de un vistazo. Hoy es el u\u0301ltimo di\u0301a antes de conocer<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-8-julio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  8 julio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJuly 8, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5539 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-julio-2025\/\">\n\t\t\t\tComentario de Mercados |  3 julio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa capacidad de observar sin juzgar es la forma m\u00e1s alta de inteligencia.\u201d Krishnamurti Los mercados de un vistazo. A nivel macro, sin lugar a duda la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-julio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  3 julio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJuly 3, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5499 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-junio-2025\/\">\n\t\t\t\tComentario de Mercados |  24 junio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLa guerra no es un fen\u00f3meno independiente, sino la continuaci\u00f3n de la pol\u00edtica por diferentes medios.\u201d Carl P. G. von Clausewitz Los mercados de un vistazo. Al<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-24-junio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  24 junio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 24, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5525 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-av-ideas-para-diversificar-las-carteras-de-renta-fija\/\">\n\t\t\t\tFinaccess Value AV: Ideas para diversificar las carteras de renta fija\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por el equipo de Finaccess Value AV Nos encontramos en un mundo inestable donde los mercados est\u00e1n claramente marcados por la volatilidad derivada de las tensiones geopol\u00edticas<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/finaccess-value-av-ideas-para-diversificar-las-carteras-de-renta-fija\/\" aria-label=\"Read more about Finaccess Value AV: Ideas para diversificar las carteras de renta fija\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 20, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5520 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/dividendo-con-futuro-cuchara-de-calidad-cuando-el-ruido-asusta-la-filosofia-de-finaccess-value\/\">\n\t\t\t\tDividendo con futuro &#8216;cuchara&#8217; de calidad cuando el ruido asusta, la filosof\u00eda de Finaccess Value\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Alfonso de Gregorio, director de inversiones de Finaccess Value, defiende la vigencia de una estrategia basada en dividendos sostenibles y gesti\u00f3n activa \u00bfC\u00f3mo valoran desde Finaccess la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/dividendo-con-futuro-cuchara-de-calidad-cuando-el-ruido-asusta-la-filosofia-de-finaccess-value\/\" aria-label=\"Read more about Dividendo con futuro &#8216;cuchara&#8217; de calidad cuando el ruido asusta, la filosof\u00eda de Finaccess Value\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 20, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5513 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/vision-patrimonialista-y-generacion-de-rentas-claves-del-fondo-finaccess-estrategia-dividendo-mixto\/\">\n\t\t\t\tVisi\u00f3n patrimonialista y generaci\u00f3n de rentas, claves del fondo Finaccess Estrategia Dividendo Mixto\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Visi\u00f3n patrimonialista y generaci\u00f3n de rentas, claves del fondo Finaccess Estrategia Dividendo Mixto.-\u00a0 En un momento en el que los inversores priorizan la estabilidad, la previsibilidad de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/vision-patrimonialista-y-generacion-de-rentas-claves-del-fondo-finaccess-estrategia-dividendo-mixto\/\" aria-label=\"Read more about Visi\u00f3n patrimonialista y generaci\u00f3n de rentas, claves del fondo Finaccess Estrategia Dividendo Mixto\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 19, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5518 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-inversion-esg-bajo-la-lupa\/\">\n\t\t\t\tLa inversi\u00f3n ESG, bajo la lupa\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>El p\u00e9ndulo sobre estos activos en Europa se ha movido a un punto m\u00e1s pragm\u00e1tico e inteligente y menos extremista. En los \u00faltimos tiempos hemos asistido a<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/la-inversion-esg-bajo-la-lupa\/\" aria-label=\"Read more about La inversi\u00f3n ESG, bajo la lupa\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 14, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5492 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-junio-2025\/\">\n\t\t\t\tComentario de Mercados |  10 junio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cSi lograste enga\u00f1ar a una persona, no quiere decir que sea tonta, quiere decir que confi\u00f3 en ti m\u00e1s de lo que te merec\u00edas.\u201d Charles Bukowski Los<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-10-junio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  10 junio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 10, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5463 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-junio-2025\/\">\n\t\t\t\tComentario de Mercados |  3 junio 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cSi lograste enga\u00f1ar a una persona, no quiere decir que sea tonta, quiere decir que confi\u00f3 en ti m\u00e1s de lo que te merec\u00edas.\u201d Charles Bukowski Los<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-3-junio-2025\/\" aria-label=\"Read more about Comentario de Mercados |  3 junio 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 3, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5478 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/oportunidades-de-inversion-tras-el-apagon-electrico\/\">\n\t\t\t\tOportunidades de inversi\u00f3n tras el apag\u00f3n el\u00e9ctrico\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Pilar Bravo (Finaccess Value): Oportunidades de inversi\u00f3n tras el apag\u00f3n el\u00e9ctrico.-\u00a0El reciente apag\u00f3n el\u00e9ctrico registrado en\u00a0Espa\u00f1a\u00a0\u2014cuyas causas a\u00fan no han sido determinadas\u2014 ha puesto de manifiesto la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/oportunidades-de-inversion-tras-el-apagon-electrico\/\" aria-label=\"Read more about Oportunidades de inversi\u00f3n tras el apag\u00f3n el\u00e9ctrico\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 2, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5425 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-mayo-2025\/\">\n\t\t\t\tComentario de Mercados |  27 mayo 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cLos dos guerreros m\u00e1s poderosos son la paciencia y el tiempo.\u201d Leon Tolstoi Los mercados de un vistazo. Los mercados estaban demasiado complacientes. Eso debi\u00f3 de pensar<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-27-mayo-2025\/\" aria-label=\"Read more about Comentario de Mercados |  27 mayo 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 27, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5439 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/lo-que-hizo-biden-de-subir-el-gasto\/\">\n\t\t\t\tLo que hizo Biden de subir el gasto en la parte m\u00e1s madura del ciclo, va en contra de toda l\u00f3gica. Varios de los problemas que afrontamos hoy tienen su origen en esa decisi\u00f3n\u00bb\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>David, \u00bfse presenta a nuestros lectores, por favor? \u201cMe llamo\u00a0David Ardura, soy CoDirector de Inversiones de\u00a0Finaccess Value, llevo trabajando en mercados 27 a\u00f1os, de los cuales los<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/lo-que-hizo-biden-de-subir-el-gasto\/\" aria-label=\"Read more about Lo que hizo Biden de subir el gasto en la parte m\u00e1s madura del ciclo, va en contra de toda l\u00f3gica. Varios de los problemas que afrontamos hoy tienen su origen en esa decisi\u00f3n\u00bb\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 25, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5411 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-20-mayo-2025\/\">\n\t\t\t\tComentario de Mercados |  20 mayo 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEs peligroso tener raz\u00f3n cuando el gobierno est\u00e1 equivocado.\u201d Voltaire Los mercados de un vistazo. Ni siquiera la rebaja de la m\u00e1xima calificaci\u00f3n crediticia de EE.UU por<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-20-mayo-2025\/\" aria-label=\"Read more about Comentario de Mercados |  20 mayo 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 20, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5454 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/invertir-por-dividendos-estabilidad-y-rentabilidad-en-tiempos-de-incertidumbre\/\">\n\t\t\t\tInvertir por dividendos, estabilidad y rentabilidad en tiempos de incertidumbre\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Alfonso de Gregorio (Finaccess Value):Invertir por dividendos, estabilidad y rentabilidad en tiempos de incertidumbre.-\u00a0Entrevista a Alfonso de Gregorio, director de inversiones de Finaccess Value, en el podcast\u00a0Tiempo<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/invertir-por-dividendos-estabilidad-y-rentabilidad-en-tiempos-de-incertidumbre\/\" aria-label=\"Read more about Invertir por dividendos, estabilidad y rentabilidad en tiempos de incertidumbre\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 16, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5396 post type-post status-publish format-standard hentry category-comentario-mercados tag-comentario-mercados tag-noticia\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-mayo-2025\/\">\n\t\t\t\tComentario de Mercados |  13 mayo 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u201cEl conocimiento es poder, y aquellos que buscan aprender tendr\u00e1n una ventaja.\u201d VICTOR HUGO Los mercados de un vistazo. Pues resulta que, despu\u00e9s de toda la volatilidad<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/comentario-mercados\/comentario-de-mercados-13-mayo-2025\/\" aria-label=\"Read more about Comentario de Mercados |  13 mayo 2025\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 13, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5444 post type-post status-publish format-standard hentry category-prensa tag-noticias\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-momento-de-invertir-en-una-estrategia-de-generacion-de-rentas\/\">\n\t\t\t\t\u00bfEs momento de invertir en una estrategia de generaci\u00f3n de rentas?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En el pasado webinar organizado por EFPA Espa\u00f1a, exploramos c\u00f3mo la estrategia de generaci\u00f3n de rentas puede adaptarse a diferentes perfiles de riesgo, su comportamiento en contextos<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/finaccessvalue.es\/en\/prensa\/es-momento-de-invertir-en-una-estrategia-de-generacion-de-rentas\/\" aria-label=\"Read more about \u00bfEs momento de invertir en una estrategia de generaci\u00f3n de rentas?\" tabindex=\"-1\">\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 12, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mant\u00e9nte al d\u00eda Comunicaci\u00f3n Todas Audios Comentario Mercados Prensa V\u00eddeos Comentario de Mercados | 13 enero 2026 \u2022 enero 13, 2026 \u201cLa pereza viaja tan despacio que la pobreza no tarda en alcanzarla.\u201d Benjamin Franklin Descargar AVISO LEGAL: La informaci\u00f3n contenida en el presente documento ha sido preparada por Finaccess Value Agencia de Valores SA. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-433","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/pages\/433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/comments?post=433"}],"version-history":[{"count":122,"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/pages\/433\/revisions"}],"predecessor-version":[{"id":5875,"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/pages\/433\/revisions\/5875"}],"wp:attachment":[{"href":"https:\/\/finaccessvalue.es\/en\/wp-json\/wp\/v2\/media?parent=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}